{"id":359,"date":"2023-01-26T17:27:06","date_gmt":"2023-01-26T16:27:06","guid":{"rendered":"https:\/\/konekan.fr\/?page_id=359"},"modified":"2024-09-22T18:54:54","modified_gmt":"2024-09-22T16:54:54","slug":"homepage","status":"publish","type":"page","link":"https:\/\/konekan.fr\/","title":{"rendered":"Lucas Guichard, portfolio d&rsquo;un d\u00e9veloppeur"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"359\" class=\"elementor elementor-359\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17d99f86 elementor-section-full_width elementor-section-content-top elementor-section-stretched elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"17d99f86\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:396,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/splash_screen_laboratory_v1.png&quot;},{&quot;id&quot;:1087,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Lobby_weed_farm.png&quot;},{&quot;id&quot;:951,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/tractor_whith8turret.webp&quot;},{&quot;id&quot;:908,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Screen-de-la-map.webp&quot;},{&quot;id&quot;:1085,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Dead_buddy.webp&quot;},{&quot;id&quot;:948,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Destructed_house.webp&quot;},{&quot;id&quot;:907,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Playertypes.webp&quot;},{&quot;id&quot;:1560,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Screenshot-2024-08-28-225849.png&quot;},{&quot;id&quot;:1482,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Screenshot-2024-07-09-121233-min.webp&quot;},{&quot;id&quot;:1495,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/aRZ9bT.webp&quot;},{&quot;id&quot;:1269,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/encadre_panorama-min.png&quot;},{&quot;id&quot;:1354,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/FH_Bird_hd.gif&quot;},{&quot;id&quot;:1465,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/image.png&quot;},{&quot;id&quot;:1564,&quot;url&quot;:&quot;https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Screenshot-2024-08-28-230047.png&quot;}],&quot;background_slideshow_transition_duration&quot;:400,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;out&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48f0cf1e\" data-id=\"48f0cf1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71e41e1 elementor-widget__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"71e41e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Game<br>Development<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-725c8f33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"725c8f33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c247695\" data-id=\"c247695\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73451ee1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"73451ee1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qui suis-je?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58b2b3bc elementor-widget elementor-widget-heading\" data-id=\"58b2b3bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00ab Salut moi, c'est Lucas ! Jeune d\u00e9veloppeur motiv\u00e9 \u00e0 r\u00e9aliser de grandes choses ! Depuis tout petit le code me passionne et j'ai compris que je voudrais en vivre quand j'ai cod\u00e9 mes premiers jeux sur scratch\u2026 C'\u00e9tait en 2012 ! \n<br><br>\n      Aujourd'hui le code me donne toujours autant de frisson et je n'imagine pas tout ce qu'il me r\u00e9serve encore. Pour en apprendre plus sur moi, visitez ce site tranquillement ou contactez-moi. \u00bb<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3924e0bc elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3924e0bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a4d4bb8\" data-id=\"1a4d4bb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32048fff elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"32048fff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quelques chiffres sympathiques :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c5b8687 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c5b8687\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5c412bf1\" data-id=\"5c412bf1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11e2600e elementor-widget__width-auto elementor-widget elementor-widget-counter\" data-id=\"11e2600e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Premier contact avec le code (HTML\/CSS &amp; Scratch)<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"10\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> <\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5375867c elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"5375867c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ans<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-16bb32e1\" data-id=\"16bb32e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f3912cd elementor-widget elementor-widget-counter\" data-id=\"4f3912cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Ann\u00e9es d'\u00e9tudes en informatique<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"4\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> <\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3254d34b elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"3254d34b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ans<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4541c09\" data-id=\"4541c09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d16739f elementor-widget elementor-widget-counter\" data-id=\"6d16739f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Vainqueur de la WonderJam hiver 2023 <\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1\" data-from-value=\"114\" data-delimiter=\",\">114<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68d74188 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"68d74188\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\/114<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7317c58\" data-id=\"7317c58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46ecf2c8 elementor-widget elementor-widget-counter\" data-id=\"46ecf2c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Langages maitris\u00e9s<br><a href=\"https:\/\/konekan.fr\/index.php\/lucasguichard\/#mes-langages\">voir lesquels...<\/a><\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"12\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1506c7b6 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"1506c7b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">+<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-556746de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"556746de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c2c9bab\" data-id=\"4c2c9bab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37b27c5e e-transform elementor-widget elementor-widget-heading\" data-id=\"37b27c5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:180,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">,,<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ebd469a elementor-testimonial--tablet-align-center elementor-widget-tablet__width-inherit elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"7ebd469a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view_tablet&quot;:&quot;1&quot;,&quot;slides_per_view_mobile&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:10000,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper-container\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tLucas, au del\u00e0 de ses qualit\u00e9s humaines qui en font quelqu'un de tr\u00e8s agr\u00e9able avec qui travailler, est un technicien redoutable qui sait mettre \u00e0 l\u2019\u0153uvre les meilleures solutions techniques qui se font pour les diff\u00e9rents besoins et contextes auquel il est confront\u00e9.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/konekan.fr\/wp-content\/uploads\/2023\/01\/1657206030356.jpeg\" alt=\"&lt;a href=&quot;https:\/\/www.linkedin.com\/in\/maxencesendral\/&quot;&gt;Maxence&lt;\/a&gt;\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\"><a href=\"https:\/\/www.linkedin.com\/in\/maxencesendral\/\">Maxence<\/a><\/span><span class=\"elementor-testimonial__title\">Expert Marketing Digital & Technique chez Sohoros.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tLucas est le genre d'\u00eatre humain que l'on aimerait rencontrer plus souvent. J'ai eu l'occasion de travailler avec lui sur des projets ambitieux et, clairement, son jeune \u00e2ge \u00e9tait inversement proportionnel \u00e0 son exp\u00e9rience. Un code de grande qualit\u00e9, une capacit\u00e9 d'adaptation exemplaire, une passion et une d\u00e9brouillardise qui font r\u00eaver : Lucas a toutes les comp\u00e9tences requises pour \u00e9voluer sur des projets \u00e0 responsabilit\u00e9s. Laissez lui 1 an d'apprentissage purement technique et vous remarquerez que ses comp\u00e9tences ne seront que d\u00e9cupl\u00e9es par sa volont\u00e9. Un plaisir d'avancer avec lui.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/konekan.fr\/wp-content\/uploads\/2023\/01\/1670582721436.jpeg\" alt=\"&lt;a href=&quot;https:\/\/www.linkedin.com\/in\/clement-gdrd\/&quot;&gt;Cl\u00e9ment Godard&lt;\/a&gt;\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\"><a href=\"https:\/\/www.linkedin.com\/in\/clement-gdrd\/\">Cl\u00e9ment Godard<\/a><\/span><span class=\"elementor-testimonial__title\">Fondateur du r\u00e9seau icon<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00e9c\u00e9dent<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Suivant<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54dd9d2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54dd9d2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-636fdcc8\" data-id=\"636fdcc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ea05319 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"6ea05319\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1987 post type-post status-publish format-standard has-post-thumbnail hentry category-game_dev category-other_en tag-projet-perso-en tag-rust-en\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/konekan.fr\/index.php\/en\/2025\/05\/22\/vertex-launcher-en\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/konekan.fr\/wp-content\/uploads\/2025\/05\/VertexLauncherLogo_trimed-300x300.png\" class=\"attachment-medium size-medium wp-image-1977\" alt=\"Logo du logiciel Vertex\" srcset=\"https:\/\/konekan.fr\/wp-content\/uploads\/2025\/05\/VertexLauncherLogo_trimed-300x300.png 300w, https:\/\/konekan.fr\/wp-content\/uploads\/2025\/05\/VertexLauncherLogo_trimed-150x150.png 150w, https:\/\/konekan.fr\/wp-content\/uploads\/2025\/05\/VertexLauncherLogo_trimed.png 780w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Games<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='lucasguichard127' src='https:\/\/konekan.fr\/wp-content\/litespeed\/avatar\/962b42b5e04c463989e479044c365079.jpg?ver=1787951265' srcset='https:\/\/konekan.fr\/wp-content\/litespeed\/avatar\/26fdfc10374e670c0ca3a6aeefaaf5a0.jpg?ver=1787951265 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/konekan.fr\/index.php\/en\/2025\/05\/22\/vertex-launcher-en\/\" >\n\t\t\t\t&nbsp;Vertex Launcher\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>GitHub repository Splashscreen Jeu en cours de t\u00e9l\u00e9chargement Page de jeu The challenge \u00a0 \u00a0 \u00a0 \u00a0 \u00a0The idea behind Vertex was born from a<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/konekan.fr\/index.php\/en\/2025\/05\/22\/vertex-launcher-en\/\" aria-label=\"En savoir plus sur &nbsp;Vertex Launcher\" tabindex=\"-1\" >\n\t\t\tVoir le projet \u2192\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tAucun commentaire\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1976 post type-post status-publish format-standard has-post-thumbnail hentry category-other category-game-developpement tag-projet-perso tag-rust\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/konekan.fr\/index.php\/2025\/05\/22\/vertex-launcher\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/konekan.fr\/wp-content\/uploads\/2025\/05\/VertexLauncherLogo_trimed-300x300.png\" class=\"attachment-medium size-medium wp-image-1977\" alt=\"Logo du logiciel Vertex\" srcset=\"https:\/\/konekan.fr\/wp-content\/uploads\/2025\/05\/VertexLauncherLogo_trimed-300x300.png 300w, https:\/\/konekan.fr\/wp-content\/uploads\/2025\/05\/VertexLauncherLogo_trimed-150x150.png 150w, https:\/\/konekan.fr\/wp-content\/uploads\/2025\/05\/VertexLauncherLogo_trimed.png 780w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Autre<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='lucasguichard127' src='https:\/\/konekan.fr\/wp-content\/litespeed\/avatar\/962b42b5e04c463989e479044c365079.jpg?ver=1787951265' srcset='https:\/\/konekan.fr\/wp-content\/litespeed\/avatar\/26fdfc10374e670c0ca3a6aeefaaf5a0.jpg?ver=1787951265 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/konekan.fr\/index.php\/2025\/05\/22\/vertex-launcher\/\" >\n\t\t\t\tVertex Launcher\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vertex est un launcher open-source et 100\u2009% data-driven. Il permet \u00e0 tous les d\u00e9veloppeurs d&rsquo;avoir enfin leur propre launcher et qui ne n\u00e9cessite aucune ligne de code.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/konekan.fr\/index.php\/2025\/05\/22\/vertex-launcher\/\" aria-label=\"En savoir plus sur Vertex Launcher\" tabindex=\"-1\" >\n\t\t\tVoir le projet \u2192\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tAucun commentaire\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1851 post type-post status-publish format-standard has-post-thumbnail hentry category-game_dev tag-gamejam-en tag-team-project-en tag-published-en tag-unreal-engine-en\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/konekan.fr\/index.php\/en\/2024\/08\/01\/umelies-instincts-en\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"238\" src=\"https:\/\/konekan.fr\/wp-content\/uploads\/2024\/12\/cover-300x238.png\" class=\"attachment-medium size-medium wp-image-1591\" alt=\"cover of the game\" srcset=\"https:\/\/konekan.fr\/wp-content\/uploads\/2024\/12\/cover-300x238.png 300w, https:\/\/konekan.fr\/wp-content\/uploads\/2024\/12\/cover.png 315w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Games<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='lucasguichard127' src='https:\/\/konekan.fr\/wp-content\/litespeed\/avatar\/962b42b5e04c463989e479044c365079.jpg?ver=1787951265' srcset='https:\/\/konekan.fr\/wp-content\/litespeed\/avatar\/26fdfc10374e670c0ca3a6aeefaaf5a0.jpg?ver=1787951265 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/konekan.fr\/index.php\/en\/2024\/08\/01\/umelies-instincts-en\/\" >\n\t\t\t\t&nbsp;Um\u00e9lie&rsquo;s Instincts\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>itch.io game page GMTK GameJam 2024 The Challenge Um\u00e9lie&rsquo;s Instincts is a game presented during the GMTK GameJam 2024, which had the theme \u00ab\u00a0Built to<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/konekan.fr\/index.php\/en\/2024\/08\/01\/umelies-instincts-en\/\" aria-label=\"En savoir plus sur &nbsp;Um\u00e9lie&rsquo;s Instincts\" tabindex=\"-1\" >\n\t\t\tVoir le projet \u2192\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tAucun commentaire\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c22c71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c22c71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-257c8d99\" data-id=\"257c8d99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-316d0e40 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"316d0e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Engagez-moi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14ddd2ea elementor-widget elementor-widget-heading\" data-id=\"14ddd2ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Prenez un caf\u00e9, envoyez moi un message et parlons de votre projet. Il n'y a pas de probl\u00e8me, que des solutions !<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe62c59 elementor-widget elementor-widget-heading\" data-id=\"2fe62c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"mailto:lucasguichard@konekan.fr\">lucasguichard@konekan.fr<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>GameDevelopment Qui suis-je? \u00ab Salut moi, c&rsquo;est Lucas ! Jeune d\u00e9veloppeur motiv\u00e9 \u00e0 r\u00e9aliser de grandes choses ! Depuis tout petit le code me passionne et j&rsquo;ai compris que je voudrais en vivre quand j&rsquo;ai cod\u00e9 mes premiers jeux sur scratch\u2026 C&rsquo;\u00e9tait en 2012 ! Aujourd&rsquo;hui le code me donne toujours autant de frisson et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-359","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Salut moi c&#039;est Lucas Guichard. Venez d\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m&#039;ont fait gagner en exp\u00e9rience.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/konekan.fr\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"konekan - Pas de probl\u00e8me, que des solutions\" \/>\n\t\t<meta property=\"og:type\" content=\"website\" \/>\n\t\t<meta property=\"og:title\" content=\"Lucas Guichard, portfolio de d\u00e9veloppeur - konekan\" \/>\n\t\t<meta property=\"og:description\" content=\"Salut moi c&#039;est Lucas Guichard. Venez d\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m&#039;ont fait gagner en exp\u00e9rience.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/konekan.fr\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lucas Guichard, portfolio de d\u00e9veloppeur - konekan\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Salut moi c&#039;est Lucas Guichard. Venez d\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m&#039;ont fait gagner en exp\u00e9rience.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/konekan.fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/konekan.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/#listItem\",\"name\":\"Lucas Guichard, portfolio d&rsquo;un d\\u00e9veloppeur\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/#listItem\",\"position\":2,\"name\":\"Lucas Guichard, portfolio d&rsquo;un d\\u00e9veloppeur\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/konekan.fr#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/#organization\",\"name\":\"konekan\",\"description\":\"Pas de probl\\u00e8me, que des solutions\",\"url\":\"https:\\\/\\\/konekan.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/konekan.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-portraitDeMoi-scaled-e1676157618267.jpg\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/konekan.fr\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/index.php\\\/author\\\/lucasguichard127\\\/#author\",\"url\":\"https:\\\/\\\/konekan.fr\\\/index.php\\\/author\\\/lucasguichard127\\\/\",\"name\":\"lucasguichard127\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/#authorImage\",\"url\":\"https:\\\/\\\/konekan.fr\\\/wp-content\\\/litespeed\\\/avatar\\\/ff39f25e032bc82f4327f0c645617cf4.jpg?ver=1787951259\",\"width\":96,\"height\":96,\"caption\":\"lucasguichard127\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/#webpage\",\"url\":\"https:\\\/\\\/konekan.fr\\\/\",\"name\":\"Lucas Guichard, portfolio de d\\u00e9veloppeur - konekan\",\"description\":\"Salut moi c'est Lucas Guichard. Venez d\\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m'ont fait gagner en exp\\u00e9rience.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/konekan.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/konekan.fr\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/konekan.fr\\\/index.php\\\/author\\\/lucasguichard127\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/konekan.fr\\\/index.php\\\/author\\\/lucasguichard127\\\/#author\"},\"datePublished\":\"2023-01-26T17:27:06+01:00\",\"dateModified\":\"2024-09-22T18:54:54+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/konekan.fr\\\/#website\",\"url\":\"https:\\\/\\\/konekan.fr\\\/\",\"name\":\"konekan\",\"alternateName\":\"Lucas guichard - portfolio\",\"description\":\"Pas de probl\\u00e8me, que des solutions\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/konekan.fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Lucas Guichard, portfolio de d\u00e9veloppeur - konekan","description":"Salut moi c'est Lucas Guichard. Venez d\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m'ont fait gagner en exp\u00e9rience.","canonical_url":"https:\/\/konekan.fr\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/konekan.fr\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/konekan.fr#listItem","position":1,"name":"Home","item":"https:\/\/konekan.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/konekan.fr\/#listItem","name":"Lucas Guichard, portfolio d&rsquo;un d\u00e9veloppeur"}},{"@type":"ListItem","@id":"https:\/\/konekan.fr\/#listItem","position":2,"name":"Lucas Guichard, portfolio d&rsquo;un d\u00e9veloppeur","previousItem":{"@type":"ListItem","@id":"https:\/\/konekan.fr#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/konekan.fr\/#organization","name":"konekan","description":"Pas de probl\u00e8me, que des solutions","url":"https:\/\/konekan.fr\/","logo":{"@type":"ImageObject","url":"https:\/\/konekan.fr\/wp-content\/uploads\/2023\/02\/cropped-portraitDeMoi-scaled-e1676157618267.jpg","@id":"https:\/\/konekan.fr\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/konekan.fr\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/konekan.fr\/index.php\/author\/lucasguichard127\/#author","url":"https:\/\/konekan.fr\/index.php\/author\/lucasguichard127\/","name":"lucasguichard127","image":{"@type":"ImageObject","@id":"https:\/\/konekan.fr\/#authorImage","url":"https:\/\/konekan.fr\/wp-content\/litespeed\/avatar\/ff39f25e032bc82f4327f0c645617cf4.jpg?ver=1787951259","width":96,"height":96,"caption":"lucasguichard127"}},{"@type":"WebPage","@id":"https:\/\/konekan.fr\/#webpage","url":"https:\/\/konekan.fr\/","name":"Lucas Guichard, portfolio de d\u00e9veloppeur - konekan","description":"Salut moi c'est Lucas Guichard. Venez d\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m'ont fait gagner en exp\u00e9rience.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/konekan.fr\/#website"},"breadcrumb":{"@id":"https:\/\/konekan.fr\/#breadcrumblist"},"author":{"@id":"https:\/\/konekan.fr\/index.php\/author\/lucasguichard127\/#author"},"creator":{"@id":"https:\/\/konekan.fr\/index.php\/author\/lucasguichard127\/#author"},"datePublished":"2023-01-26T17:27:06+01:00","dateModified":"2024-09-22T18:54:54+02:00"},{"@type":"WebSite","@id":"https:\/\/konekan.fr\/#website","url":"https:\/\/konekan.fr\/","name":"konekan","alternateName":"Lucas guichard - portfolio","description":"Pas de probl\u00e8me, que des solutions","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/konekan.fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"konekan - Pas de probl\u00e8me, que des solutions","og:type":"website","og:title":"Lucas Guichard, portfolio de d\u00e9veloppeur - konekan","og:description":"Salut moi c'est Lucas Guichard. Venez d\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m'ont fait gagner en exp\u00e9rience.","og:url":"https:\/\/konekan.fr\/","twitter:card":"summary_large_image","twitter:title":"Lucas Guichard, portfolio de d\u00e9veloppeur - konekan","twitter:description":"Salut moi c'est Lucas Guichard. Venez d\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m'ont fait gagner en exp\u00e9rience."},"aioseo_meta_data":{"post_id":"359","title":"Lucas Guichard, portfolio de d\u00e9veloppeur - konekan","description":"Salut moi c'est Lucas Guichard. Venez d\u00e9couvrir ma micro entreprise Konekan ainsi que tous mes projets qui m'ont fait gagner en exp\u00e9rience.","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"website","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2023-02-16 16:16:11","updated":"2026-09-01 02:27:05","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/konekan.fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLucas Guichard, portfolio d\u2019un d\u00e9veloppeur\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/konekan.fr"},{"label":"Lucas Guichard, portfolio d&rsquo;un d\u00e9veloppeur","link":"https:\/\/konekan.fr\/"}],"_links":{"self":[{"href":"https:\/\/konekan.fr\/index.php\/wp-json\/wp\/v2\/pages\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konekan.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/konekan.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/konekan.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/konekan.fr\/index.php\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":182,"href":"https:\/\/konekan.fr\/index.php\/wp-json\/wp\/v2\/pages\/359\/revisions"}],"predecessor-version":[{"id":1578,"href":"https:\/\/konekan.fr\/index.php\/wp-json\/wp\/v2\/pages\/359\/revisions\/1578"}],"wp:attachment":[{"href":"https:\/\/konekan.fr\/index.php\/wp-json\/wp\/v2\/media?parent=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}